{"id":9352,"date":"2023-12-31T12:50:23","date_gmt":"2023-12-31T11:50:23","guid":{"rendered":"https:\/\/lumulu.de\/blog\/?p=9352"},"modified":"2024-04-19T18:00:50","modified_gmt":"2024-04-19T16:00:50","slug":"happy-new-year-felix-ano-nuevo","status":"publish","type":"post","link":"https:\/\/lumulu.de\/blog\/2023\/12\/31\/happy-new-year-felix-ano-nuevo\/","title":{"rendered":"Happy New Year in Spanien!"},"content":{"rendered":"\n<p>Liebe Blogfreunde,<\/p>\n\n\n\n<p>der Winterblues und Schmuddelwetter haben uns spontan veranlasst, uns f\u00fcr ein paar Wochen auf den Weg zu machen, um ein wenig Tapetenwechsel und ein paar Grad mehr auf der nach oben offenen Richterskala zu erleben. Noch nie waren wir um diese Jahreszeit mit dem Wohnmobil auf Tour!&nbsp;Urspr\u00fcnglich hatten wir Ende des Monats eine Reise nach Jordanien geplant, dann kamen die Auseinandersetzungen im nahen Israel dazwischen und wir entschieden uns dagegen. Unvorhergesehene Abenteuer hatten wir (wie viele von euch wissen) bereits genug auf unseren Reisen, da braucht es keine vorhersehbaren. Nun sind wir gespannt, wie uns die Reise um diese Jahreszeit gef\u00e4llt. Unsere Vorgabe: wir fahren Richtung S\u00fcden ans Mittelmeer bis es warm wird. <\/p>\n\n\n\n<div class=\"wp-block-image is-style-rounded\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3530-768x1024.jpeg\" alt=\"\" class=\"wp-image-9353\" width=\"374\" height=\"498\" srcset=\"https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3530-768x1024.jpeg 768w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3530-225x300.jpeg 225w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3530-1152x1536.jpeg 1152w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3530-rotated.jpeg 1512w\" sizes=\"(max-width: 374px) 100vw, 374px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3518-rotated.jpeg\" alt=\"\" class=\"wp-image-9354\" srcset=\"https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3518-rotated.jpeg 480w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3518-225x300.jpeg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3532-rotated.jpeg\" alt=\"\" class=\"wp-image-9355\" srcset=\"https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3532-rotated.jpeg 480w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3532-225x300.jpeg 225w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/figure><\/div>\n\n\n\n<p>Den heutigen Jahreswechsel verbringen wir nun am Meer in der N\u00e4he von Figueres, um das neue Jahr gem\u00fctlich zu begr\u00fc\u00dfen und dann standesgem\u00e4\u00df mit einem Besuch des Dal\u00ed-Museums zu beginnen.&nbsp;Wir sind vorbereitet:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3536-768x1024.jpeg\" alt=\"\" class=\"wp-image-9357\" srcset=\"https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3536-768x1024.jpeg 768w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3536-225x300.jpeg 225w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3536-1152x1536.jpeg 1152w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3536-rotated.jpeg 1512w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption>Ein Galette des rois &#8211; eine eigentlich franz\u00f6sische Tradition, die die B\u00e4cker hier auch anbieten. Mit einem ganz lieben Gru\u00df an unsere franz\u00f6sische Freundin V\u00e9ro! \ud83d\ude42<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3542-768x1024.jpeg\" alt=\"\" class=\"wp-image-9356\" srcset=\"https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3542-768x1024.jpeg 768w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3542-225x300.jpeg 225w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3542-1152x1536.jpeg 1152w, https:\/\/lumulu.de\/blog\/wp-content\/uploads\/2023\/12\/IMG_3542-rotated.jpeg 1512w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>Die traditionellen Weintrauben &#8211; 12 St\u00fcck nacheinander mit den letzten 12 Glockenschl\u00e4gen des alten Jahres essen soll Gl\u00fcck bringen. Das ist doch ein Versuch wert! <\/p>\n\n\n\n<p>So, nun kann das alte Jahr vergehen und wir sind voller Erwartungen, was uns das neue Jahr bringen wird. Wir haben 365 Tage plus einen Tag (!)  Zeit, das beste daraus zu machen. <\/p>\n\n\n\n<p>Einen guten Rutsch und f\u00fcr euch alle ein friedliches Jahr 2024!<\/p>\n\n\n\n<p>Eure Weltenbummler Barbara &amp; Paul <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Blogfreunde, der Winterblues und Schmuddelwetter haben uns spontan veranlasst, uns f\u00fcr ein paar Wochen auf den Weg zu machen, um ein wenig Tapetenwechsel und ein paar Grad mehr auf der nach oben offenen Richterskala zu erleben. Noch nie waren &hellip; <a href=\"https:\/\/lumulu.de\/blog\/2023\/12\/31\/happy-new-year-felix-ano-nuevo\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9352","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/lumulu.de\/blog\/wp-json\/wp\/v2\/posts\/9352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lumulu.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lumulu.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lumulu.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lumulu.de\/blog\/wp-json\/wp\/v2\/comments?post=9352"}],"version-history":[{"count":6,"href":"https:\/\/lumulu.de\/blog\/wp-json\/wp\/v2\/posts\/9352\/revisions"}],"predecessor-version":[{"id":9732,"href":"https:\/\/lumulu.de\/blog\/wp-json\/wp\/v2\/posts\/9352\/revisions\/9732"}],"wp:attachment":[{"href":"https:\/\/lumulu.de\/blog\/wp-json\/wp\/v2\/media?parent=9352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lumulu.de\/blog\/wp-json\/wp\/v2\/categories?post=9352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lumulu.de\/blog\/wp-json\/wp\/v2\/tags?post=9352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}